{"id":3646,"date":"2022-03-11T12:00:12","date_gmt":"2022-03-11T11:00:12","guid":{"rendered":"https:\/\/laespiral.deusto.es\/?p=3646"},"modified":"2025-04-28T20:57:10","modified_gmt":"2025-04-28T18:57:10","slug":"dicotomicos-perdidos","status":"publish","type":"post","link":"https:\/\/laespiral.deusto.es\/eu\/dicotomicos-perdidos\/","title":{"rendered":"Dicot\u00f3micos perdidos"},"content":{"rendered":"\r\n<figure><\/figure>\r\n<figure><a href=\"https:\/\/laespiral.deusto.es\/wp-content\/uploads\/2021\/04\/1.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2690\" src=\"https:\/\/laespiral.deusto.es\/wp-content\/uploads\/2021\/04\/1.png\" alt=\"\" width=\"2000\" height=\"231\" srcset=\"https:\/\/laespiral.deusto.es\/wp-content\/uploads\/2021\/04\/1.png 2000w, https:\/\/laespiral.deusto.es\/wp-content\/uploads\/2021\/04\/1-300x35.png 300w, https:\/\/laespiral.deusto.es\/wp-content\/uploads\/2021\/04\/1-1024x118.png 1024w, https:\/\/laespiral.deusto.es\/wp-content\/uploads\/2021\/04\/1-768x89.png 768w, https:\/\/laespiral.deusto.es\/wp-content\/uploads\/2021\/04\/1-1536x177.png 1536w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" \/><\/a><\/figure>\r\n<figure class=\"wp-block-image is-resized\"><a href=\"https:\/\/laespiral.deusto.es\/wp-content\/uploads\/2022\/03\/mauro-tandoi-iNsnCOQ_sG8-unsplash-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3647\" src=\"https:\/\/laespiral.deusto.es\/wp-content\/uploads\/2022\/03\/mauro-tandoi-iNsnCOQ_sG8-unsplash-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1705\" srcset=\"https:\/\/laespiral.deusto.es\/wp-content\/uploads\/2022\/03\/mauro-tandoi-iNsnCOQ_sG8-unsplash-scaled.jpg 2560w, https:\/\/laespiral.deusto.es\/wp-content\/uploads\/2022\/03\/mauro-tandoi-iNsnCOQ_sG8-unsplash-300x200.jpg 300w, https:\/\/laespiral.deusto.es\/wp-content\/uploads\/2022\/03\/mauro-tandoi-iNsnCOQ_sG8-unsplash-1024x682.jpg 1024w, https:\/\/laespiral.deusto.es\/wp-content\/uploads\/2022\/03\/mauro-tandoi-iNsnCOQ_sG8-unsplash-768x512.jpg 768w, https:\/\/laespiral.deusto.es\/wp-content\/uploads\/2022\/03\/mauro-tandoi-iNsnCOQ_sG8-unsplash-1536x1023.jpg 1536w, https:\/\/laespiral.deusto.es\/wp-content\/uploads\/2022\/03\/mauro-tandoi-iNsnCOQ_sG8-unsplash-2048x1364.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a>\r\n<figcaption><span style=\"font-weight: 400;\">Photo by <a href=\"https:\/\/unsplash.com\/@maurotandoi?utm_source=unsplash&amp;utm_medium=referral&amp;utm_content=creditCopyText\">Mauro Tandoi<\/a> on<a href=\"https:\/\/unsplash.com\/s\/photos\/two-sides?utm_source=unsplash&amp;utm_medium=referral&amp;utm_content=creditCopyText\"> Unsplash<\/a><\/span><\/figcaption>\r\n<\/figure>\r\n\r\n<p>Vivimos en una civilizaci\u00f3n binaria, estamos configurados en base dos. Dicot\u00f3micos perdidos, eso es lo que somos. Para todo manejamos dos opciones: s\u00ed o no, cerca o lejos, bueno o malo, ganar o perder, noche o d\u00eda. A\u00f1adir una tercera variable lo complicar\u00eda todo de modo extraordinario. En una hipot\u00e9tica sociedad ternaria nuestros premios Nobel ser\u00edan como ni\u00f1os de pecho, qu\u00e9 decir de otros mundos construidos en base cuatro, cinco, etc\u00e9tera.<\/p>\r\n<p>Quiz\u00e1 el secreto del \u00e9xito (relativo) de la religi\u00f3n cat\u00f3lica sea la introducci\u00f3n sibilina de la tercera persona en el misterio de la Trinidad. Hablar solo del Padre y del Hijo ser\u00eda moverse en ese entorno familiar de a dos, a\u00f1adir al Esp\u00edritu Santo es entrar en el arcano de otra dimensi\u00f3n (y el que lo entienda que lo explique).<\/p>\r\n<p>Hace casi sesenta a\u00f1os Umberto Eco dividi\u00f3 a los estudiosos de la cultura de masas en \u2013c\u00f3mo no\u2013 dos sensibilidades en su libro <em>Apocal\u00edpticos e integrados<\/em> (leerlo debe ser como tragar polvorones con la boca seca). Son dos t\u00e9rminos que encajan en la situaci\u00f3n actual como sin\u00f3nimos de conspiranoicos y normalitos; dicho sea normalitos sin intenci\u00f3n peyorativa, solo con \u00e1nimo de mantener la proporci\u00f3n sil\u00e1bica. Aclaro que, como simple ser binario que soy, simpatizo con los \u201cnormales\u201d o integrados.<\/p>\r\n<p>La naturaleza dual intr\u00ednseca al ser humano puede nacer de nuestra propia morfolog\u00eda, ya que somos sim\u00e9tricos (por fuera al menos) y tenemos dos ojos, dos brazos o dos piernas. Esa simetr\u00eda da lugar al (aparente) doble comportamiento, dependiendo de la orientaci\u00f3n, de nuestra figura reflejada en un espejo. En el sentido horizontal, a lo ancho, los lados se invierten, lo que en la realidad est\u00e1 a la derecha es izquierda para el tipo del espejo; en cambio en el sentido vertical no hay tal inversi\u00f3n y la cabeza reflejada sigue estando arriba, igual que a este lado del espejo.<\/p>\r\n<p>Esa especie de trampantojo me ha sugerido dos cosas: por un lado, que nuestra comprensi\u00f3n del mundo est\u00e1 condicionada por la visi\u00f3n estereosc\u00f3pica que nos es propia; y por otro, que a pesar de que en cada elecci\u00f3n sean solo dos las opciones que contemplemos, bastan para que en la sempiterna sucesi\u00f3n de dilemas que es el laberinto de la vida lo l\u00f3gico sea perderse.<\/p>","protected":false},"excerpt":{"rendered":"<p>Vivimos en una civilizaci\u00f3n binaria, estamos configurados en base dos. Dicot\u00f3micos perdidos, eso es lo que somos. Para todo manejamos dos opciones: s\u00ed o no, cerca o lejos, bueno o malo, ganar o perder, noche o d\u00eda. A\u00f1adir una tercera variable lo complicar\u00eda todo de modo extraordinario. En una hipot\u00e9tica sociedad ternaria nuestros premios Nobel [&hellip;]<\/p>\n","protected":false},"author":37,"featured_media":3647,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[17],"tags":[794],"class_list":{"0":"post-3646","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-zona-critica","8":"tag-duroderroer","9":"entry"},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/laespiral.deusto.es\/eu\/wp-json\/wp\/v2\/posts\/3646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laespiral.deusto.es\/eu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laespiral.deusto.es\/eu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laespiral.deusto.es\/eu\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/laespiral.deusto.es\/eu\/wp-json\/wp\/v2\/comments?post=3646"}],"version-history":[{"count":2,"href":"https:\/\/laespiral.deusto.es\/eu\/wp-json\/wp\/v2\/posts\/3646\/revisions"}],"predecessor-version":[{"id":3649,"href":"https:\/\/laespiral.deusto.es\/eu\/wp-json\/wp\/v2\/posts\/3646\/revisions\/3649"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laespiral.deusto.es\/eu\/wp-json\/wp\/v2\/media\/3647"}],"wp:attachment":[{"href":"https:\/\/laespiral.deusto.es\/eu\/wp-json\/wp\/v2\/media?parent=3646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laespiral.deusto.es\/eu\/wp-json\/wp\/v2\/categories?post=3646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laespiral.deusto.es\/eu\/wp-json\/wp\/v2\/tags?post=3646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}