{"id":211,"count":2,"description":"","link":"https:\/\/laespiral.deusto.es\/tag\/zinema\/","name":"zinema","slug":"zinema","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/laespiral.deusto.es\/tag\/zinema\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/laespiral.deusto.es\\\/eu\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/211\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/laespiral.deusto.es\\\/eu\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/laespiral.deusto.es\\\/eu\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/laespiral.deusto.es\\\/tag\\\/zinema\\\/#listItem\",\"name\":\"zinema\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/laespiral.deusto.es\\\/tag\\\/zinema\\\/#listItem\",\"position\":2,\"name\":\"zinema\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/laespiral.deusto.es\\\/eu\\\/#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/laespiral.deusto.es\\\/eu\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/211\\\/#collectionpage\",\"url\":\"https:\\\/\\\/laespiral.deusto.es\\\/eu\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/211\\\/\",\"name\":\"zinema - La Espiral\",\"inLanguage\":\"eu-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/laespiral.deusto.es\\\/eu\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/laespiral.deusto.es\\\/eu\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/211\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/laespiral.deusto.es\\\/eu\\\/#organization\",\"name\":\"La Espiral\",\"description\":\"No es solo una revista\",\"url\":\"https:\\\/\\\/laespiral.deusto.es\\\/eu\\\/\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/laespiral.deusto.es\\\/eu\\\/#website\",\"url\":\"https:\\\/\\\/laespiral.deusto.es\\\/eu\\\/\",\"name\":\"La Espiral\",\"description\":\"No es solo una revista\",\"inLanguage\":\"eu-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/laespiral.deusto.es\\\/eu\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"zinema - La Espiral","description":"","canonical_url":"https:\/\/laespiral.deusto.es\/tag\/zinema\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/laespiral.deusto.es\/eu\/wp-json\/wp\/v2\/tags\/211\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/laespiral.deusto.es\/eu\/#listItem","position":1,"name":"Home","item":"https:\/\/laespiral.deusto.es\/eu\/","nextItem":{"@type":"ListItem","@id":"https:\/\/laespiral.deusto.es\/tag\/zinema\/#listItem","name":"zinema"}},{"@type":"ListItem","@id":"https:\/\/laespiral.deusto.es\/tag\/zinema\/#listItem","position":2,"name":"zinema","previousItem":{"@type":"ListItem","@id":"https:\/\/laespiral.deusto.es\/eu\/#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/laespiral.deusto.es\/eu\/wp-json\/wp\/v2\/tags\/211\/#collectionpage","url":"https:\/\/laespiral.deusto.es\/eu\/wp-json\/wp\/v2\/tags\/211\/","name":"zinema - La Espiral","inLanguage":"eu-ES","isPartOf":{"@id":"https:\/\/laespiral.deusto.es\/eu\/#website"},"breadcrumb":{"@id":"https:\/\/laespiral.deusto.es\/eu\/wp-json\/wp\/v2\/tags\/211\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/laespiral.deusto.es\/eu\/#organization","name":"La Espiral","description":"No es solo una revista","url":"https:\/\/laespiral.deusto.es\/eu\/"},{"@type":"WebSite","@id":"https:\/\/laespiral.deusto.es\/eu\/#website","url":"https:\/\/laespiral.deusto.es\/eu\/","name":"La Espiral","description":"No es solo una revista","inLanguage":"eu-ES","publisher":{"@id":"https:\/\/laespiral.deusto.es\/eu\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/laespiral.deusto.es\/eu\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tzinema\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/laespiral.deusto.es\/eu\/"},{"label":"zinema","link":"https:\/\/laespiral.deusto.es\/tag\/zinema\/"}],"_links":{"self":[{"href":"https:\/\/laespiral.deusto.es\/eu\/wp-json\/wp\/v2\/tags\/211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laespiral.deusto.es\/eu\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/laespiral.deusto.es\/eu\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/laespiral.deusto.es\/eu\/wp-json\/wp\/v2\/posts?tags=211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}